{"id":1821,"date":"2020-10-05T19:59:05","date_gmt":"2020-10-05T19:59:05","guid":{"rendered":"https:\/\/simansolucionesintegrales.com\/wordpress\/?page_id=1821"},"modified":"2023-02-01T17:52:59","modified_gmt":"2023-02-01T22:52:59","slug":"siman-xpress","status":"publish","type":"page","link":"https:\/\/simansolucionesintegrales.com\/siman\/siman-xpress\/","title":{"rendered":"Siman Xpress"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1821\" class=\"elementor elementor-1821\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-01aa672 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"01aa672\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2d589a1\" data-id=\"2d589a1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c05daae elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c05daae\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d8a07e4\" data-id=\"d8a07e4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-94bd84d elementor-widget elementor-widget-image\" data-id=\"94bd84d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"171\" src=\"https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2020\/10\/LogoPNG04-300x171.png\" class=\"attachment-medium size-medium wp-image-1838\" alt=\"\" srcset=\"https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2020\/10\/LogoPNG04-300x171.png 300w, https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2020\/10\/LogoPNG04-768x439.png 768w, https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2020\/10\/LogoPNG04.png 770w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-8485e4d\" data-id=\"8485e4d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4bd9de6 e-grid-align-right elementor-shape-rounded elementor-grid-0 elementor-invisible elementor-widget elementor-widget-social-icons\" data-id=\"4bd9de6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;headShake&quot;}\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-animation-pulse-grow elementor-repeater-item-7f3d486\" href=\"https:\/\/web.facebook.com\/Simanxpress\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-facebook\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-animation-pulse-grow elementor-repeater-item-003ba9d\" href=\"https:\/\/www.instagram.com\/siman.xpress\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-youtube elementor-animation-pulse-grow elementor-repeater-item-4e12ae8\" href=\"https:\/\/www.youtube.com\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Youtube<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-youtube\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-505bb4c elementor-align-end elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-invisible elementor-widget elementor-widget-icon-list\" data-id=\"505bb4c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/simansolucionesintegrales.com\/wordpress\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-reply\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Siman Soluciones Integrales<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-67f7aaf elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"67f7aaf\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_gallery&quot;:[{&quot;id&quot;:1833,&quot;url&quot;:&quot;https:\\\/\\\/simansolucionesintegrales.com\\\/wordpress\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/imgport006-min.jpg&quot;},{&quot;id&quot;:1898,&quot;url&quot;:&quot;https:\\\/\\\/simansolucionesintegrales.com\\\/wordpress\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/imgport0010-min.jpg&quot;},{&quot;id&quot;:1959,&quot;url&quot;:&quot;https:\\\/\\\/simansolucionesintegrales.com\\\/wordpress\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/imgport0013-min.jpg&quot;},{&quot;id&quot;:1960,&quot;url&quot;:&quot;https:\\\/\\\/simansolucionesintegrales.com\\\/wordpress\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/imgport0014-min.jpg&quot;},{&quot;id&quot;:1834,&quot;url&quot;:&quot;https:\\\/\\\/simansolucionesintegrales.com\\\/wordpress\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/imgport007-min.jpg&quot;}],&quot;background_slideshow_ken_burns&quot;:&quot;yes&quot;,&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_duration&quot;:5000,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_slideshow_transition_duration&quot;:500,&quot;background_slideshow_ken_burns_zoom_direction&quot;:&quot;in&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4f5427e\" data-id=\"4f5427e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-48488f6 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"48488f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:&quot;200&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Sobre nosotros<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e2f0c68 elementor-widget elementor-widget-text-editor\" data-id=\"e2f0c68\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p align=\"justify\">Brindamos servicio de log\u00edstica integral a trav\u00e9s de Courier. Asimismo, sumamos a nuestro servicio de Courier el almacenamiento y cobranza. Para otorgarle facilidad y tranquilidad a nuestros clientes en Lima Metropolitana y Callao.<br \/>Trabajamos con un equipo din\u00e1mico y comprometido en brindar un servicio de calidad y excelencia.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ce39127 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"ce39127\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#contact\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Cotiza<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5029b64 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5029b64\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-a3975f6\" data-id=\"a3975f6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5ac0cdd elementor-widget elementor-widget-heading\" data-id=\"5ac0cdd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">\u00bfBuscas un servicio courier de calidad?<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7c38317\" data-id=\"7c38317\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2b271a4 animated-fast elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"2b271a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;tada&quot;,&quot;_animation_delay&quot;:300}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Ll\u00e1manos al<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-6ea08a3\" data-id=\"6ea08a3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-df26ba4 elementor-align-start elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-invisible elementor-widget elementor-widget-icon-list\" data-id=\"df26ba4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;bounce&quot;}\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-mobile-alt\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">918 490 629<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-45819595 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"45819595\" data-element_type=\"section\" data-e-type=\"section\" id=\"about\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2deb3fe3\" data-id=\"2deb3fe3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-591a5ed8 elementor-widget elementor-widget-heading\" data-id=\"591a5ed8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nuestro Objetivo<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4acff79 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"4acff79\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-18a2cdd3 elementor-widget elementor-widget-text-editor\" data-id=\"18a2cdd3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ser el socio estrat\u00e9gico en cuanto a la log\u00edsta de nuestros clientes seg\u00fan sus necesidades, brindando garant\u00eda, confianza y puntualidad en la entrega de sus productos.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8f28b72\" data-id=\"8f28b72\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cf5a1d5 elementor-widget elementor-widget-image\" data-id=\"cf5a1d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2020\/10\/imgport0011-min.jpg\" class=\"elementor-animation-grow-rotate attachment-full size-full wp-image-1942\" alt=\"SimanXpress - Nuestro Objetivo\" srcset=\"https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2020\/10\/imgport0011-min.jpg 1920w, https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2020\/10\/imgport0011-min-300x200.jpg 300w, https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2020\/10\/imgport0011-min-1024x683.jpg 1024w, https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2020\/10\/imgport0011-min-768x512.jpg 768w, https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2020\/10\/imgport0011-min-1536x1024.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8a0928b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8a0928b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-66db5b3\" data-id=\"66db5b3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-59034a6 elementor-widget elementor-widget-heading\" data-id=\"59034a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation_mobile&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Reduce costos, <font color=\"yellow\">almacenamiento y servicio de cobranza gratis<\/font><\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-476b965 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"476b965\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-46b0bf8\" data-id=\"46b0bf8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0de0563 elementor-section-full_width elementor-reverse-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"0de0563\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-5984241\" data-id=\"5984241\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-28f4bf5 elementor-mobile-align-end elementor-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-invisible elementor-widget elementor-widget-icon-list\" data-id=\"28f4bf5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;bounce&quot;}\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-motorcycle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Delivery<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-18dbd6c\" data-id=\"18dbd6c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-457b868 elementor-align-center elementor-tablet-align-center elementor-mobile-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-invisible elementor-widget elementor-widget-icon-list\" data-id=\"457b868\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;bounce&quot;}\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-warehouse\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Almacen<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-367aebf\" data-id=\"367aebf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c2c9d77 elementor-align-center elementor-tablet-align-center elementor-mobile-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-invisible elementor-widget elementor-widget-icon-list\" data-id=\"c2c9d77\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;bounce&quot;}\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-cash-register\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Cobranza<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-30663ac7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"30663ac7\" data-element_type=\"section\" data-e-type=\"section\" id=\"rates\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4229738c\" data-id=\"4229738c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2763f85e elementor-widget elementor-widget-heading\" data-id=\"2763f85e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">E-Commerce<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c618744 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"3c618744\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1e54f990 elementor-widget elementor-widget-text-editor\" data-id=\"1e54f990\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p align=\"justify\">Nuestro servicio E-Commerce tiene como prop\u00f3sito, brindar un servicio integral para emprendimientos en l\u00ednea. Por lo cual en nuestro servicio de Courier para E-Commerce incluimos gratis el servicio de Almacenamiento y servicio de Cobranza.<\/p><p>Para brindar a nuestros clientes mayor facilidad y tranquilidad a la hora de realizar sus ventas. Le informamos el estado de sus productos en almac\u00e9n; Asimismo, las cobranzas realizadas por nuestro personal a la hora de entrega se abonan dentro de las 24hr.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1894856b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1894856b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-9852713 elementor-invisible\" data-id=\"9852713\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;swing&quot;,&quot;animation_mobile&quot;:&quot;tada&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-51692cb4 elementor-widget elementor-widget-heading\" data-id=\"51692cb4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-large\">S\/ 10.00<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e69051f elementor-widget elementor-widget-heading\" data-id=\"e69051f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Gratis Almac\u00e9n y cobranza<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1e8ad89e elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"1e8ad89e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">A partir de 10 env\u00edos a m\u00e1s (Solo Lima Metropolitana)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-443b4a75 elementor-widget elementor-widget-button\" data-id=\"443b4a75\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#contact\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Mas informaci\u00f3n<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-15b72ea elementor-invisible\" data-id=\"15b72ea\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;swing&quot;,&quot;animation_mobile&quot;:&quot;tada&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fe03a8b elementor-widget elementor-widget-heading\" data-id=\"fe03a8b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-large\">S\/ 13.00<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-91a6a4f elementor-widget elementor-widget-heading\" data-id=\"91a6a4f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Gratis Almac\u00e9n y cobranza<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-35fc7ee elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"35fc7ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">A partir de 5 env\u00edos (Solo Lima Metropolitana)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2033ec7 elementor-widget elementor-widget-button\" data-id=\"2033ec7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#contact\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Mas informaci\u00f3n<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-54b50ec elementor-invisible\" data-id=\"54b50ec\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;swing&quot;,&quot;animation_mobile&quot;:&quot;tada&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c82a229 elementor-widget elementor-widget-heading\" data-id=\"c82a229\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-large\">S\/ 15.00<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9341b71 elementor-widget elementor-widget-heading\" data-id=\"9341b71\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Gratis Almac\u00e9n y cobranza<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-83f0af4 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"83f0af4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Menos de 5 env\u00edos (Solo Lima Metropolitana)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6a08165 elementor-widget elementor-widget-button\" data-id=\"6a08165\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#contact\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Mas informaci\u00f3n<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-b44158d elementor-widget elementor-widget-heading\" data-id=\"b44158d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\"><font face=\"capriola\">Solicita tu tarifario segun tu zona al<\/font><b> <font color=\"blue\">  918 490 629 <\/font><\/b><\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4c8fc724 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4c8fc724\" data-element_type=\"section\" data-e-type=\"section\" id=\"training\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-3fd37fb3\" data-id=\"3fd37fb3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a62016e elementor-widget elementor-widget-heading\" data-id=\"a62016e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Conf\u00eda en <\/br>Siman Xpress<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-56b47a69 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"56b47a69\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-50bf6111 elementor-widget elementor-widget-text-editor\" data-id=\"50bf6111\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p align=\"justify\">Somos el socio log\u00edstico estrat\u00e9gico que necesitas para la entrega de tus productos de forma segura y oportuna a tus clientes. Ahorrando costos de almacen y cobranza.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-36854d5a\" data-id=\"36854d5a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4c2b9d73 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"4c2b9d73\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Calidad<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Puntualidad<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Seguridad<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Honestidad<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Responsabilidad<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Inmediatez en la tranferencia de cobranzas<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Informe del estado de almacenamiento<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Mejora Continua<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4b13a9b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4b13a9b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9f71655\" data-id=\"9f71655\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-33d6fd5 elementor-widget elementor-widget-heading\" data-id=\"33d6fd5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation_mobile&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Sus pedidos, tus productos, <font color=\"yellow\">nuestro compromiso<\/font><\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5fbdd62e elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5fbdd62e\" data-element_type=\"section\" data-e-type=\"section\" id=\"clients\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-2445e29b\" data-id=\"2445e29b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7ccc84e0 elementor-widget elementor-widget-heading\" data-id=\"7ccc84e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Confian en nosotros<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2aee2152 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"2aee2152\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b49e226 elementor-widget elementor-widget-text-editor\" data-id=\"5b49e226\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ustedes se encargan de las ventas, nosotros de la entrega.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-56ec8a23\" data-id=\"56ec8a23\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c08a3f4 elementor-position-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"c08a3f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;bounce&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.facebook.com\/STAR-En-LINEa-103413111428479\" target=\"_blank\" tabindex=\"-1\"><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2022\/06\/Cliente_Star-en-Linea-150x150.jpg\" class=\"elementor-animation-pulse-grow attachment-thumbnail size-thumbnail wp-image-2401\" alt=\"Cliente Star en Linea - Siman Xpress\" srcset=\"https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2022\/06\/Cliente_Star-en-Linea-150x150.jpg 150w, https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2022\/06\/Cliente_Star-en-Linea-298x300.jpg 298w, https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2022\/06\/Cliente_Star-en-Linea-1017x1024.jpg 1017w, https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2022\/06\/Cliente_Star-en-Linea-768x773.jpg 768w, https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2022\/06\/Cliente_Star-en-Linea.jpg 1036w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h6 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.facebook.com\/STAR-En-LINEa-103413111428479\" target=\"_blank\">Star en L\u00ednea<\/a><\/h6><p class=\"elementor-image-box-description\">Accesorios<\/br>@STAR En LINEa<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c27260 elementor-position-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"4c27260\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;bounce&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.facebook.com\/unalukaCom\/\" target=\"_blank\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2022\/06\/Cliente_Unaluka-150x150.png\" class=\"elementor-animation-pulse-grow attachment-thumbnail size-thumbnail wp-image-2402\" alt=\"Cliente UnaLuka - Siman Xpress\" srcset=\"https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2022\/06\/Cliente_Unaluka-150x150.png 150w, https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2022\/06\/Cliente_Unaluka-300x300.png 300w, https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2022\/06\/Cliente_Unaluka-1024x1024.png 1024w, https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2022\/06\/Cliente_Unaluka-768x768.png 768w, https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2022\/06\/Cliente_Unaluka-1536x1536.png 1536w, https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2022\/06\/Cliente_Unaluka.png 1970w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h6 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.facebook.com\/unalukaCom\/\" target=\"_blank\">Unaluka<\/a><\/h6><p class=\"elementor-image-box-description\">Productos Tecnol\u00f3gico<\/br>@unalukaCom<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3641b84b elementor-position-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"3641b84b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;bounce&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/web.facebook.com\/GALUAcalzadoinfantil\" target=\"_blank\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2022\/06\/Cliente_Flabril-150x150.jpg\" class=\"elementor-animation-pulse-grow attachment-thumbnail size-thumbnail wp-image-2403\" alt=\"Cliente Flabril - Siman Xpress\" srcset=\"https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2022\/06\/Cliente_Flabril-150x150.jpg 150w, https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2022\/06\/Cliente_Flabril-300x300.jpg 300w, https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2022\/06\/Cliente_Flabril-768x768.jpg 768w, https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2022\/06\/Cliente_Flabril.jpg 960w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h6 class=\"elementor-image-box-title\"><a href=\"https:\/\/web.facebook.com\/GALUAcalzadoinfantil\" target=\"_blank\">Flabril<\/a><\/h6><p class=\"elementor-image-box-description\">Art\u00edculos del hogar<\/br>@Importacionesflabril<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-315f6d1 elementor-position-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"315f6d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;bounce&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.facebook.com\/Novedadescrismafer\/\" target=\"_blank\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2022\/06\/CrisMafer-150x150.jpg\" class=\"elementor-animation-pulse-grow attachment-thumbnail size-thumbnail wp-image-2409\" alt=\"Cliente CrisMafer - Siman Xpress\" srcset=\"https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2022\/06\/CrisMafer-150x150.jpg 150w, https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2022\/06\/CrisMafer-300x300.jpg 300w, https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2022\/06\/CrisMafer-1024x1024.jpg 1024w, https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2022\/06\/CrisMafer-768x768.jpg 768w, https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2022\/06\/CrisMafer-1536x1536.jpg 1536w, https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2022\/06\/CrisMafer.jpg 2048w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h6 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.facebook.com\/Novedadescrismafer\/\" target=\"_blank\">Novedades CrisMafer<\/a><\/h6><p class=\"elementor-image-box-description\">Publicidad y marketing<\/br>@Novedadescrismafer<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-6e6db59\" data-id=\"6e6db59\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bc294af elementor-position-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"bc294af\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;bounce&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.facebook.com\/Medfis-Day-103607654788985\" target=\"_blank\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2022\/06\/Cliente_Medfis-Day-150x150.jpg\" class=\"elementor-animation-pulse-grow attachment-thumbnail size-thumbnail wp-image-2400\" alt=\"Cliente Medfis Day - Siman Xpress\" srcset=\"https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2022\/06\/Cliente_Medfis-Day-150x150.jpg 150w, https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2022\/06\/Cliente_Medfis-Day-300x298.jpg 300w, https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2022\/06\/Cliente_Medfis-Day-768x763.jpg 768w, https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2022\/06\/Cliente_Medfis-Day.jpg 960w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h6 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.facebook.com\/Medfis-Day-103607654788985\" target=\"_blank\">Medfis day<\/a><\/h6><p class=\"elementor-image-box-description\">Deportes y Ocio<\/br>@Medfis Day<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-29241ff elementor-position-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"29241ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;bounce&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/web.facebook.com\/waylluyjabones\" target=\"_blank\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2020\/10\/imgWaylluy-150x150.jpg\" class=\"elementor-animation-pulse-grow attachment-thumbnail size-thumbnail wp-image-1877\" alt=\"Cliente Waylluy - Siman Xpress\" srcset=\"https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2020\/10\/imgWaylluy-150x150.jpg 150w, https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2020\/10\/imgWaylluy-300x300.jpg 300w, https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2020\/10\/imgWaylluy.jpg 423w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h6 class=\"elementor-image-box-title\"><a href=\"https:\/\/web.facebook.com\/waylluyjabones\" target=\"_blank\">Waylluy<\/a><\/h6><p class=\"elementor-image-box-description\">Salud y Belleza<\/br>@Waylluyjabones<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-11af210 elementor-position-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"11af210\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;bounce&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/web.facebook.com\/GALUAcalzadoinfantil\" target=\"_blank\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2020\/10\/imgGalua-150x150.jpg\" class=\"elementor-animation-pulse-grow attachment-thumbnail size-thumbnail wp-image-1878\" alt=\"Cliente Galua - Siman Xpress\" srcset=\"https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2020\/10\/imgGalua-150x150.jpg 150w, https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2020\/10\/imgGalua-300x300.jpg 300w, https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2020\/10\/imgGalua.jpg 640w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h6 class=\"elementor-image-box-title\"><a href=\"https:\/\/web.facebook.com\/GALUAcalzadoinfantil\" target=\"_blank\">Galua<\/a><\/h6><p class=\"elementor-image-box-description\">Calzado Infantil<\/br>@GALUAcalzadoinfantil<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b9a1d61 elementor-position-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"b9a1d61\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;bounce&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.facebook.com\/Naduoficial\/\" target=\"_blank\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2022\/06\/Cliente_Nadu-150x150.png\" class=\"elementor-animation-pulse-grow attachment-thumbnail size-thumbnail wp-image-2410\" alt=\"Cliente Nadu - Siman Xpress\" srcset=\"https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2022\/06\/Cliente_Nadu-150x150.png 150w, https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2022\/06\/Cliente_Nadu-300x300.png 300w, https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2022\/06\/Cliente_Nadu-1024x1024.png 1024w, https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2022\/06\/Cliente_Nadu-768x768.png 768w, https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2022\/06\/Cliente_Nadu.png 1200w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h6 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.facebook.com\/Naduoficial\/\" target=\"_blank\">Nad\u00fa<\/a><\/h6><p class=\"elementor-image-box-description\">Tienda de alimentos naturales<\/br>@Naduoficial  <\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-14ff59b\" data-id=\"14ff59b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-49ce04bb elementor-position-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"49ce04bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;bounce&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/web.facebook.com\/ChiaraArtesana\" target=\"_blank\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2020\/10\/imgChiaraArtesana-150x150.jpg\" class=\"elementor-animation-pulse-grow attachment-thumbnail size-thumbnail wp-image-1879\" alt=\"Cliente Chiara Artesana - Siman Xpress\" srcset=\"https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2020\/10\/imgChiaraArtesana-150x150.jpg 150w, https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2020\/10\/imgChiaraArtesana-300x300.jpg 300w, https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2020\/10\/imgChiaraArtesana-768x768.jpg 768w, https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2020\/10\/imgChiaraArtesana.jpg 960w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h6 class=\"elementor-image-box-title\"><a href=\"https:\/\/web.facebook.com\/ChiaraArtesana\" target=\"_blank\">Chiara Artesana<\/a><\/h6><p class=\"elementor-image-box-description\">Salud y Belleza<\/br>@ChiaraArtesana<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ef8c733 elementor-position-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"2ef8c733\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;bounce&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/web.facebook.com\/caritoinsumosjabones\" target=\"_blank\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2020\/10\/imgCarito-150x150.jpg\" class=\"elementor-animation-pulse-grow attachment-thumbnail size-thumbnail wp-image-1880\" alt=\"Cliente Carito - Siman Xpress\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h6 class=\"elementor-image-box-title\"><a href=\"https:\/\/web.facebook.com\/caritoinsumosjabones\" target=\"_blank\">Carito<\/a><\/h6><p class=\"elementor-image-box-description\">Salud \/ Belleza<\/br>@caritoinsumosjabones<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-35851693 elementor-position-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"35851693\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;bounce&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.facebook.com\/yorkaaromasyarte\/\" target=\"_blank\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2022\/06\/Cliente_Yorka-Aromas-y-Arte-150x150.jpg\" class=\"elementor-animation-pulse-grow attachment-thumbnail size-thumbnail wp-image-2404\" alt=\"Cliente Yorka - Siman Xpress\" srcset=\"https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2022\/06\/Cliente_Yorka-Aromas-y-Arte-150x150.jpg 150w, https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2022\/06\/Cliente_Yorka-Aromas-y-Arte-300x300.jpg 300w, https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2022\/06\/Cliente_Yorka-Aromas-y-Arte.jpg 338w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h6 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.facebook.com\/yorkaaromasyarte\/\" target=\"_blank\">Yorka Aromas y Arte<\/a><\/h6><p class=\"elementor-image-box-description\">Tienda de arte y manualidadesa<\/br>@yorkaaromasyarte<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e9f09b0 elementor-position-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"e9f09b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;bounce&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.facebook.com\/CSegura0276\/\" target=\"_blank\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2022\/06\/Cliente_Compra-Segura-150x150.jpg\" class=\"elementor-animation-pulse-grow attachment-thumbnail size-thumbnail wp-image-2411\" alt=\"Cliente Compra Segura - Siman Xpress\" srcset=\"https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2022\/06\/Cliente_Compra-Segura-150x150.jpg 150w, https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2022\/06\/Cliente_Compra-Segura-300x298.jpg 300w, https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2022\/06\/Cliente_Compra-Segura-768x763.jpg 768w, https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2022\/06\/Cliente_Compra-Segura.jpg 952w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h6 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.facebook.com\/CSegura0276\/\" target=\"_blank\">Compra Segura<\/a><\/h6><p class=\"elementor-image-box-description\">Producto\/servicio<\/br>@CSegura0276 <\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1c7a44d5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1c7a44d5\" data-element_type=\"section\" data-e-type=\"section\" id=\"gallery\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-26451c12\" data-id=\"26451c12\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-371079fd elementor-widget elementor-widget-heading\" data-id=\"371079fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Tus clientes, nuestros clientes<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5a238d3b elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"5a238d3b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-aca4bf5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"aca4bf5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-inner-column elementor-element elementor-element-47e47aa\" data-id=\"47e47aa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1350507 elementor-widget elementor-widget-text-editor\" data-id=\"1350507\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p align=\"justify\">Nuestros clientes son nuestra raz\u00f3n de ser, as\u00ed como los clientes de nuestros clientes.\nPor ello nos comprometemos en llevar tus productos a sus hogares, garantizando seguridad, rapidez y confianza.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-0ecd231\" data-id=\"0ecd231\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-18dac30d elementor-arrows-position-inside elementor-invisible elementor-widget elementor-widget-image-carousel\" data-id=\"18dac30d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;4&quot;,&quot;slides_to_show_tablet&quot;:&quot;1&quot;,&quot;slides_to_show_mobile&quot;:&quot;1&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;_animation&quot;:&quot;bounceInRight&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrusel de im\u00e1genes\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 31\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2020\/10\/imgDelivery001-min-144x300.jpg\" alt=\"Nuestros Clientes01\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 31\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2020\/10\/imgDelivery002-min-144x300.jpg\" alt=\"Nuestros Clientes02\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 de 31\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2020\/10\/imgDelivery009-min-144x300.jpg\" alt=\"Nuestros Clientes03\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 de 31\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2020\/10\/imgDelivery013-min-144x300.jpg\" alt=\"Nuestros Clientes04\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 de 31\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2020\/10\/imgDelivery021-min-144x300.jpg\" alt=\"Nuestros Clientes05\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 de 31\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2020\/10\/imgDelivery023-min-144x300.jpg\" alt=\"Nuestros Clientes06\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 de 31\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2020\/10\/imgDelivery026-min-144x300.jpg\" alt=\"Nuestros Clientes07\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 de 31\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2020\/10\/imgDelivery029-min-144x300.jpg\" alt=\"Nuestros Clientes08\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 de 31\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2020\/10\/imgDelivery034-min-144x300.jpg\" alt=\"Nuestros Clientes09\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 de 31\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2020\/10\/imgDelivery036-min-144x300.jpg\" alt=\"Nuestros Clientes10\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 de 31\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2020\/10\/imgDelivery037-min-144x300.jpg\" alt=\"Nuestros Clientes11\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"12 de 31\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2020\/10\/imgDelivery005-min-144x300.jpg\" alt=\"Nuestros Clientes12\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"13 de 31\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2020\/10\/imgDelivery006-min-144x300.jpg\" alt=\"Nuestros Clientes13\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"14 de 31\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2020\/10\/imgDelivery011-min-144x300.jpg\" alt=\"Nuestros Clientes14\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"15 de 31\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2020\/10\/imgDelivery012-min-144x300.jpg\" alt=\"Nuestros Clientes15\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"16 de 31\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2020\/10\/imgDelivery014-min-144x300.jpg\" alt=\"Nuestros Clientes16\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"17 de 31\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2020\/10\/imgDelivery017-min-144x300.jpg\" alt=\"Nuestros Clientes17\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"18 de 31\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2020\/10\/imgDelivery018-min-144x300.jpg\" alt=\"Nuestros Clientes18\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"19 de 31\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2020\/10\/imgDelivery019-min-144x300.jpg\" alt=\"Nuestros Clientes19\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"20 de 31\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2020\/10\/imgDelivery022-min-144x300.jpg\" alt=\"Nuestros Clientes20\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"21 de 31\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2020\/10\/imgDelivery024-min-144x300.jpg\" alt=\"Nuestros Clientes21\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"22 de 31\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2020\/10\/imgDelivery025-min-144x300.jpg\" alt=\"Nuestros Clientes22\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"23 de 31\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2020\/10\/imgDelivery027-min-144x300.jpg\" alt=\"Nuestros Clientes23\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"24 de 31\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2020\/10\/imgDelivery028-min-144x300.jpg\" alt=\"Nuestros Clientes24\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"25 de 31\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2020\/10\/imgDelivery030-min-144x300.jpg\" alt=\"Nuestros Clientes25\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"26 de 31\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2020\/10\/imgDelivery031-min-144x300.jpg\" alt=\"Nuestros Clientes26\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"27 de 31\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2020\/10\/imgDelivery032-min-144x300.jpg\" alt=\"Nuestros Clientes27\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"28 de 31\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2020\/10\/imgDelivery033-min-144x300.jpg\" alt=\"Nuestros Clientes28\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"29 de 31\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2020\/10\/imgDelivery035-min-144x300.jpg\" alt=\"Nuestros Clientes29\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"30 de 31\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2020\/10\/imgDelivery003-min-144x300.jpg\" alt=\"Nuestros Clientes30\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"31 de 31\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2020\/10\/imgDelivery004-min-144x300.jpg\" alt=\"Nuestros Clientes31\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f206c04 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f206c04\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6185c7e\" data-id=\"6185c7e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dcd1d6e elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"dcd1d6e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;,&quot;_animation_mobile&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Juntos reactivaremos tu Empresa y la Econom\u00eda de nuestro Pa\u00eds<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1232ac15 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1232ac15\" data-element_type=\"section\" data-e-type=\"section\" id=\"contact\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-26eaaa2c\" data-id=\"26eaaa2c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-69f80da elementor-widget elementor-widget-image\" data-id=\"69f80da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"163\" src=\"https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2020\/10\/LogoPNG02-300x163.png\" class=\"attachment-medium size-medium wp-image-1689\" alt=\"\" srcset=\"https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2020\/10\/LogoPNG02-300x163.png 300w, https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2020\/10\/LogoPNG02.png 584w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b22a04e elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"b22a04e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-78ba57bf elementor-widget elementor-widget-text-editor\" data-id=\"78ba57bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p align=\"justify\"><b>Siman Xpress<\/b> es una unidad de negocio de Siman Soluciones Integrales SAC. Para conocer m\u00e1s acerca de nuestra empresa y nuestros servicios envi\u00e9 un correo o ll\u00e1menos.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-61a50bf0 elementor-shape-circle e-grid-align-left e-grid-align-mobile-center elementor-grid-0 elementor-invisible elementor-widget elementor-widget-social-icons\" data-id=\"61a50bf0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;bounce&quot;}\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook-f elementor-repeater-item-5xovbrc\" href=\"https:\/\/web.facebook.com\/Simanxpress\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook-f<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-facebook-f\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-iggt43m\" href=\"https:\/\/www.instagram.com\/siman.xpress\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-51ec6ba elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"51ec6ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/simansolucionesintegrales.com\/wordpress\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-reply\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Regresar a Siman Soluciones<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f8a5171 elementor-absolute elementor-widget elementor-widget-heading\" data-id=\"1f8a5171\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Siman Xpress<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-25e6bb76\" data-id=\"25e6bb76\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2b43ce3b elementor-widget elementor-widget-heading\" data-id=\"2b43ce3b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Cont\u00e1ctanos<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2f6f4c4a elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"2f6f4c4a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-23b876ec elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"23b876ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.google.com\/maps\/place\/Huacllan+4899,+Los+Olivos+15304\/@-11.9776349,-77.0804411,17z\/data=!4m5!3m4!1s0x9105ce6a7d06d963:0x390501e7de0c002b!8m2!3d-11.9788838!4d-77.0800227\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-map-marker-alt\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Calle huacllan 4899, Parque Naranjal - Los Olivos - Lima<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"mailto:info.delivery@simanxpress.com\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-envelope\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">info.delivery@simanxpress.com<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-mobile-alt\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">918-490-629<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-mobile-alt\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">981-454-462<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-792a70eb\" data-id=\"792a70eb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-59779525 elementor-widget elementor-widget-heading\" data-id=\"59779525\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Solicita una llamada<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b1e87ee elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"3b1e87ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-46a73453 elementor-widget elementor-widget-shortcode\" data-id=\"46a73453\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div class=\"wpforms-container \" id=\"wpforms-1691\"><form id=\"wpforms-form-1691\" class=\"wpforms-validate wpforms-form\" data-formid=\"1691\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/siman\/wp-json\/wp\/v2\/pages\/1821\" data-token=\"524be3b98b76b16070d1229af870cd25\" data-token-time=\"1788312249\"><noscript class=\"wpforms-error-noscript\">Por favor, activa JavaScript en tu navegador para completar este formulario.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-1691-field_0-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"0\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-1691-field_0\">Nombre completo <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-1691-field_0\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][0]\" placeholder=\"Nombre Completo*\" required><\/div><div id=\"wpforms-1691-field_1-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"1\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-1691-field_1\">Correo <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-1691-field_1\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][1]\" placeholder=\"Correo*\" spellcheck=\"false\" required><\/div><div id=\"wpforms-1691-field_5-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-classic\" data-field-id=\"5\"><label class=\"wpforms-field-label\" for=\"wpforms-1691-field_5\">Servicios <span class=\"wpforms-required-label\">*<\/span><\/label><select id=\"wpforms-1691-field_5\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][5]\" required=\"required\"><option value=\"Courier\"  class=\"choice-1 depth-1\"  >Courier<\/option><option value=\"E-Commerce\"  class=\"choice-2 depth-1\"  >E-Commerce<\/option><option value=\"Taxi Carga\"  class=\"choice-3 depth-1\"  >Taxi Carga<\/option><option value=\"Delivery\"  class=\"choice-4 depth-1\"  >Delivery<\/option><\/select><\/div><div id=\"wpforms-1691-field_3-container\" class=\"wpforms-field wpforms-field-number\" data-field-id=\"3\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-1691-field_3\">T\u00e9lefono <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"number\" id=\"wpforms-1691-field_3\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][3]\" placeholder=\"T\u00e9lefono \/ Celular*\" step=\"any\" required><\/div><div id=\"wpforms-1691-field_2-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"2\"><textarea id=\"wpforms-1691-field_2\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][2]\" placeholder=\"D\u00e9jenos su mensaje*\" required><\/textarea><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-field wpforms-field-hp\"><label for=\"wpforms-1691-field-hp\" class=\"wpforms-field-label\">Website<\/label><input type=\"text\" name=\"wpforms[hp]\" id=\"wpforms-1691-field-hp\" class=\"wpforms-field-medium\"><\/div><div class=\"wpforms-recaptcha-container wpforms-is-recaptcha wpforms-is-recaptcha-type-v2\" ><div class=\"g-recaptcha\" data-sitekey=\"6Ldl8FcaAAAAAJMgUHyZFs4i-Ofb-GTelcGSI4fV\"><\/div><input type=\"text\" name=\"g-recaptcha-hidden\" class=\"wpforms-recaptcha-hidden\" style=\"position:absolute!important;clip:rect(0,0,0,0)!important;height:1px!important;width:1px!important;border:0!important;overflow:hidden!important;padding:0!important;margin:0!important;\" data-rule-recaptcha=\"1\"><\/div><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"1691\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/simansolucionesintegrales.com\/siman\/wp-json\/wp\/v2\/pages\/1821\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-1691\" class=\"wpforms-submit wpf-blue-background\" data-alt-text=\"Enviar...\" data-submit-text=\"\u00a1Ll\u00e1menme!\" aria-live=\"assertive\" value=\"wpforms-submit\">\u00a1Ll\u00e1menme!<\/button><\/div><\/form><\/div>  <!-- .wpforms-container --><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f5c61e0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f5c61e0\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e3d75fa\" data-id=\"e3d75fa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ec8d00f elementor-widget elementor-widget-heading\" data-id=\"ec8d00f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Copyright 2020 \u00a9 Dise\u00f1o Web por <a href=\"https:\/\/www.opensourceperu.com\" target=\"_blank\">OPSORU<\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Facebook Instagram Youtube Siman Soluciones Integrales Sobre nosotros Brindamos servicio de log\u00edstica integral a trav\u00e9s de Courier. Asimismo, sumamos a nuestro servicio de Courier el almacenamiento y cobranza. Para otorgarle facilidad y tranquilidad a nuestros clientes en Lima Metropolitana y Callao.Trabajamos con un equipo din\u00e1mico y comprometido en brindar un servicio de calidad y excelencia. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-1821","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Siman Xpress | Siman Xpress www.simanxpress.com<\/title>\n<meta name=\"description\" content=\"Brindamos servicio de E-Commerce, envio por delivery de sus productos a tus clientes, adem\u00e1s gratis almac\u00e9n y cobranza. | cont\u00e1ctanos al 918490629 \/ 981454462\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/simansolucionesintegrales.com\/siman\/siman-xpress\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Siman Soluciones Integrales Siman Xpress |\" \/>\n<meta property=\"og:description\" content=\"Brindamos servicio de log\u00edstica integral a trav\u00e9s de Courier. Asimismo, sumamos a nuestro servicio de Courier el almacenamiento y caja. Para otorgarle facilidad y tranquilidad a nuestros clientes en Lima Metropolitana y Callao.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/simansolucionesintegrales.com\/siman\/siman-xpress\/\" \/>\n<meta property=\"og:site_name\" content=\"Siman Soluciones Integrales\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SimanSoluciones\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-01T22:52:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2020\/10\/Simanxpress-min.png\" \/>\n\t<meta property=\"og:image:width\" content=\"940\" \/>\n\t<meta property=\"og:image:height\" content=\"710\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"14 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/simansolucionesintegrales.com\\\/siman\\\/siman-xpress\\\/\",\"url\":\"https:\\\/\\\/simansolucionesintegrales.com\\\/siman\\\/siman-xpress\\\/\",\"name\":\"Siman Xpress | Siman Xpress www.simanxpress.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/simansolucionesintegrales.com\\\/siman\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/simansolucionesintegrales.com\\\/siman\\\/siman-xpress\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/simansolucionesintegrales.com\\\/siman\\\/siman-xpress\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/simansolucionesintegrales.com\\\/wordpress\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/LogoPNG04-300x171.png\",\"datePublished\":\"2020-10-05T19:59:05+00:00\",\"dateModified\":\"2023-02-01T22:52:59+00:00\",\"description\":\"Brindamos servicio de E-Commerce, envio por delivery de sus productos a tus clientes, adem\u00e1s gratis almac\u00e9n y cobranza. | cont\u00e1ctanos al 918490629 \\\/ 981454462\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/simansolucionesintegrales.com\\\/siman\\\/siman-xpress\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/simansolucionesintegrales.com\\\/siman\\\/siman-xpress\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/simansolucionesintegrales.com\\\/siman\\\/siman-xpress\\\/#primaryimage\",\"url\":\"https:\\\/\\\/simansolucionesintegrales.com\\\/wordpress\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/LogoPNG04-300x171.png\",\"contentUrl\":\"https:\\\/\\\/simansolucionesintegrales.com\\\/wordpress\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/LogoPNG04-300x171.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/simansolucionesintegrales.com\\\/siman\\\/siman-xpress\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/simansolucionesintegrales.com\\\/siman\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Siman Xpress\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/simansolucionesintegrales.com\\\/siman\\\/#website\",\"url\":\"https:\\\/\\\/simansolucionesintegrales.com\\\/siman\\\/\",\"name\":\"Siman Soluciones Integrales\",\"description\":\"Servicios de control de plagas y figuraci\u00f3n para empresas\",\"publisher\":{\"@id\":\"https:\\\/\\\/simansolucionesintegrales.com\\\/siman\\\/#organization\"},\"alternateName\":\"Siman\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/simansolucionesintegrales.com\\\/siman\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/simansolucionesintegrales.com\\\/siman\\\/#organization\",\"name\":\"Siman Soluciones Integrales SAC\",\"alternateName\":\"Siman\",\"url\":\"https:\\\/\\\/simansolucionesintegrales.com\\\/siman\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/simansolucionesintegrales.com\\\/siman\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/simansolucionesintegrales.com\\\/wordpress\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Icono-del-sitio.png\",\"contentUrl\":\"https:\\\/\\\/simansolucionesintegrales.com\\\/wordpress\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Icono-del-sitio.png\",\"width\":512,\"height\":512,\"caption\":\"Siman Soluciones Integrales SAC\"},\"image\":{\"@id\":\"https:\\\/\\\/simansolucionesintegrales.com\\\/siman\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SimanSoluciones\",\"https:\\\/\\\/www.instagram.com\\\/siman.soluciones\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Siman Xpress | Siman Xpress www.simanxpress.com","description":"Brindamos servicio de E-Commerce, envio por delivery de sus productos a tus clientes, adem\u00e1s gratis almac\u00e9n y cobranza. | cont\u00e1ctanos al 918490629 \/ 981454462","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/simansolucionesintegrales.com\/siman\/siman-xpress\/","og_locale":"es_ES","og_type":"article","og_title":"Siman Soluciones Integrales Siman Xpress |","og_description":"Brindamos servicio de log\u00edstica integral a trav\u00e9s de Courier. Asimismo, sumamos a nuestro servicio de Courier el almacenamiento y caja. Para otorgarle facilidad y tranquilidad a nuestros clientes en Lima Metropolitana y Callao.","og_url":"https:\/\/simansolucionesintegrales.com\/siman\/siman-xpress\/","og_site_name":"Siman Soluciones Integrales","article_publisher":"https:\/\/www.facebook.com\/SimanSoluciones","article_modified_time":"2023-02-01T22:52:59+00:00","og_image":[{"width":940,"height":710,"url":"https:\/\/simansolucionesintegrales.com\/siman\/wp-content\/uploads\/2020\/10\/Simanxpress-min.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"14 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/simansolucionesintegrales.com\/siman\/siman-xpress\/","url":"https:\/\/simansolucionesintegrales.com\/siman\/siman-xpress\/","name":"Siman Xpress | Siman Xpress www.simanxpress.com","isPartOf":{"@id":"https:\/\/simansolucionesintegrales.com\/siman\/#website"},"primaryImageOfPage":{"@id":"https:\/\/simansolucionesintegrales.com\/siman\/siman-xpress\/#primaryimage"},"image":{"@id":"https:\/\/simansolucionesintegrales.com\/siman\/siman-xpress\/#primaryimage"},"thumbnailUrl":"https:\/\/simansolucionesintegrales.com\/wordpress\/wp-content\/uploads\/2020\/10\/LogoPNG04-300x171.png","datePublished":"2020-10-05T19:59:05+00:00","dateModified":"2023-02-01T22:52:59+00:00","description":"Brindamos servicio de E-Commerce, envio por delivery de sus productos a tus clientes, adem\u00e1s gratis almac\u00e9n y cobranza. | cont\u00e1ctanos al 918490629 \/ 981454462","breadcrumb":{"@id":"https:\/\/simansolucionesintegrales.com\/siman\/siman-xpress\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/simansolucionesintegrales.com\/siman\/siman-xpress\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/simansolucionesintegrales.com\/siman\/siman-xpress\/#primaryimage","url":"https:\/\/simansolucionesintegrales.com\/wordpress\/wp-content\/uploads\/2020\/10\/LogoPNG04-300x171.png","contentUrl":"https:\/\/simansolucionesintegrales.com\/wordpress\/wp-content\/uploads\/2020\/10\/LogoPNG04-300x171.png"},{"@type":"BreadcrumbList","@id":"https:\/\/simansolucionesintegrales.com\/siman\/siman-xpress\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/simansolucionesintegrales.com\/siman\/"},{"@type":"ListItem","position":2,"name":"Siman Xpress"}]},{"@type":"WebSite","@id":"https:\/\/simansolucionesintegrales.com\/siman\/#website","url":"https:\/\/simansolucionesintegrales.com\/siman\/","name":"Siman Soluciones Integrales","description":"Servicios de control de plagas y figuraci\u00f3n para empresas","publisher":{"@id":"https:\/\/simansolucionesintegrales.com\/siman\/#organization"},"alternateName":"Siman","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/simansolucionesintegrales.com\/siman\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/simansolucionesintegrales.com\/siman\/#organization","name":"Siman Soluciones Integrales SAC","alternateName":"Siman","url":"https:\/\/simansolucionesintegrales.com\/siman\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/simansolucionesintegrales.com\/siman\/#\/schema\/logo\/image\/","url":"https:\/\/simansolucionesintegrales.com\/wordpress\/wp-content\/uploads\/2020\/09\/Icono-del-sitio.png","contentUrl":"https:\/\/simansolucionesintegrales.com\/wordpress\/wp-content\/uploads\/2020\/09\/Icono-del-sitio.png","width":512,"height":512,"caption":"Siman Soluciones Integrales SAC"},"image":{"@id":"https:\/\/simansolucionesintegrales.com\/siman\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SimanSoluciones","https:\/\/www.instagram.com\/siman.soluciones\/"]}]}},"_links":{"self":[{"href":"https:\/\/simansolucionesintegrales.com\/siman\/wp-json\/wp\/v2\/pages\/1821","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/simansolucionesintegrales.com\/siman\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/simansolucionesintegrales.com\/siman\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/simansolucionesintegrales.com\/siman\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/simansolucionesintegrales.com\/siman\/wp-json\/wp\/v2\/comments?post=1821"}],"version-history":[{"count":105,"href":"https:\/\/simansolucionesintegrales.com\/siman\/wp-json\/wp\/v2\/pages\/1821\/revisions"}],"predecessor-version":[{"id":2447,"href":"https:\/\/simansolucionesintegrales.com\/siman\/wp-json\/wp\/v2\/pages\/1821\/revisions\/2447"}],"wp:attachment":[{"href":"https:\/\/simansolucionesintegrales.com\/siman\/wp-json\/wp\/v2\/media?parent=1821"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}